{"id":5188,"date":"2022-01-14T10:00:00","date_gmt":"2022-01-14T09:00:00","guid":{"rendered":"https:\/\/hartkorn-gewuerze.de\/blog\/?p=5188"},"modified":"2023-06-07T12:05:53","modified_gmt":"2023-06-07T10:05:53","slug":"red-cap-spende-foerdahrverein","status":"publish","type":"post","link":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/","title":{"rendered":"RED CAP meets SPENDEN SHUTTLE"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>RED CAP-Spendenaktion unterst\u00fctzt Betroffene der Hochwasserkatastrophe im Ahrtal mit <\/strong>14.500 Euro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Unvergessen sind die Bilder von Schlamm, Zerst\u00f6rung und Verzweiflung, die die Landschaft des Ahrtals nach der <strong>Hochwasserkatastrophe in der Nacht vom 14. auf den 15. Juli 2021<\/strong> pr\u00e4gten und im Anschluss \u00fcber die TV-Bildschirme flirrten oder als Push-Nachricht auf den Handys der Nation aufploppten. <strong>Gnadenlose Wassermassen<\/strong> hatten ganze Ortschaften zerst\u00f6rt und Menschen vor den Tr\u00fcmmern ihrer Existenz zur\u00fcckgelassen. Ein Schicksal, dass auch uns tief ber\u00fchrte.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"600\" height=\"398\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/red-cap-spenden-foerdahrverein-2022-hartkorn.jpg\" alt=\"Red Cap Spenden Shuttle F\u00f6rdahrverein 2022\" class=\"wp-image-5191 size-full\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/red-cap-spenden-foerdahrverein-2022-hartkorn.jpg 600w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/red-cap-spenden-foerdahrverein-2022-hartkorn-300x199.jpg 300w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/red-cap-spenden-foerdahrverein-2022-hartkorn-90x60.jpg 90w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Deshalb stand eines ganz schnell fest: Wir wollen helfen! Kurzfristig und unb\u00fcrokratisch entschieden wir also, die <strong>RED CAP-Spendenaktion<\/strong> unter dem Motto #hartkornhilft den Betroffenen der Hochwasserkatastrophe im Ahrtal zu Gute kommen zu lassen. So kam die stolze Summe von <strong>12.500 Euro<\/strong> zusammen, die die Hartkorn Gew\u00fcrzm\u00fchle dann noch einmal um <strong>2.000 Euro<\/strong> aufstockte, um sie an ein Kinderprojekt vor Ort zu spenden. Aber dazu sp\u00e4ter mehr &#8230;<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>RED CAP \u2013 Was war das noch gleich?<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Du hast noch nie von unserer j\u00e4hrlichen RED CAP-Spendenaktion geh\u00f6rt? Gar kein Problem, wir erkl\u00e4ren dir gerne, worum es dabei geht. Schau doch dazu einfach ganz fix mal auf unserem letzten <a href=\"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-hochwasserkatastrophe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">Blogbeitrag<\/span><\/a> zur Aktion vorbei. Dort findest du alle Informationen noch einmal geb\u00fcndelt. So viel k\u00f6nnen wir aber auch hier noch verraten: Auch dieses Mal waren wieder die absoluten Topseller unter den <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/gewuerzstreuer\/?typ=red-cap\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">Gew\u00fcrzstreuern<\/span><\/a> Teil der Aktion. Von <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/anis-ganz-gewuerzstreuer.html\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">Anis<\/span><\/a> \u00fcber <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/pfeffer-schwarz-gemahlen-gewuerzstreuer.html\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">schwarzen Pfeffer<\/span><\/a>, <span class=\"has-inline-color has-vivid-red-color\"><a href=\"https:\/\/hartkorn-gewuerze.de\/de\/kardamom-gemahlen-gewuerzstreuer.html\" target=\"_blank\" rel=\"noreferrer noopener\">Kardamom<\/a><\/span> und <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/kreuzkuemmel-cumin-gemahlen-gewuerzstreuer.html\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">Kreuzk\u00fcmmel<\/span><\/a> bis hin zu <span class=\"has-inline-color has-vivid-red-color\"><a href=\"https:\/\/hartkorn-gewuerze.de\/de\/zimt-gemahlen-gewuerzstreuer.html\" target=\"_blank\" rel=\"noreferrer noopener\">Zimt<\/a> <\/span>durften diese den roten Deckel tragen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Kleiner Tipp: <\/em>Die Gew\u00fcrze findest du nat\u00fcrlich auch unabh\u00e4ngig von der RED CAP-Spendenaktion im Supermarkt und im Hartkorn <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">Online-Shop<\/span><\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-white-background-color has-white-color is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hartkorn-gewuerze.de\/de\/red-cap-spende\/\"><img decoding=\"async\" width=\"1024\" height=\"328\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/dosen-hartkorn-red-cap-spende-1024x328.jpg\" alt=\"\" class=\"wp-image-4785\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/dosen-hartkorn-red-cap-spende-1024x328.jpg 1024w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/dosen-hartkorn-red-cap-spende-300x96.jpg 300w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/dosen-hartkorn-red-cap-spende-768x246.jpg 768w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/dosen-hartkorn-red-cap-spende-187x60.jpg 187w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/dosen-hartkorn-red-cap-spende.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Gesagt, getan: RED CAP-Spendenaktion zeigt sich flexibel<\/strong><\/strong><\/h3>\n\n\n\n<div style=\"height:12px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 57%\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/hartkorn-gewuerze.de\/unternehmen\/red-cap-spende-hochwasser\/\"><img decoding=\"async\" width=\"800\" height=\"301\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/hochwasser-spendenaktion-hartkorn.jpg\" alt=\"RED CAP-Spendenaktion 2021\" class=\"wp-image-4786 size-full\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/hochwasser-spendenaktion-hartkorn.jpg 800w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/hochwasser-spendenaktion-hartkorn-300x113.jpg 300w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/hochwasser-spendenaktion-hartkorn-768x289.jpg 768w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/hochwasser-spendenaktion-hartkorn-159x60.jpg 159w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Vielleicht ist es dir aufgefallen oder du hast es gelesen: In diesem Jahr gab es ein paar Ver\u00e4nderungen bei der RED CAP-Spendenaktion.<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-white-background-color has-white-color is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:27% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"292\" height=\"400\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkorn-red-cap-im-supermarkt-regal.jpg\" alt=\"Hartkorn Red Cap-Spendendosen im Supermarkt Regal. \" class=\"wp-image-5218 size-full\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkorn-red-cap-im-supermarkt-regal.jpg 292w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkorn-red-cap-im-supermarkt-regal-219x300.jpg 219w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkorn-red-cap-im-supermarkt-regal-44x60.jpg 44w\" sizes=\"(max-width: 292px) 100vw, 292px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Zum einen startete sie fr\u00fcher als sonst und unsere <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/gewuerzstreuer\/\" target=\"_blank\" rel=\"noreferrer noopener\">klassischen <\/a><span class=\"has-inline-color has-vivid-red-color\"><a href=\"https:\/\/hartkorn-gewuerze.de\/de\/gewuerzstreuer\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gew\u00fcrzstreuer<\/a> <\/span>zeigten ihre schicken roten Deckel schon im August in den Supermarktregalen und im <a href=\"https:\/\/hartkorn-gewuerze.de\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Online-Shop<\/a>. Und zum anderen gingen die Spendengelder dieses Mal nicht an ein Projekt unseres treuen Partners <a href=\"https:\/\/arche-nova.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">arche noVa e.V<\/span>.<\/a> Das lag eben daran, dass sich im Ahrtal \u2013 also quasi in unmittelbarer Nachbarschaft zu unseren Standorten Koblenz und M\u00fclheim-K\u00e4rlich eine schreckliche Hochwasserkatastrophe ereignet hatte. Da war schnelles Handeln gefordert! Wir konnten und wollten nicht auf den regul\u00e4ren Start der Aktion warten und es stand auch au\u00dfer Zweifel, dass die RED CAP-Spendengelder unbedingt den Menschen im Ahrtal eine Hilfe sein sollten.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb machten wir uns auf die Suche nach einem geeigneten Partner, der uns bei diesem Vorhaben unterst\u00fctzen k\u00f6nnte. Und wir wurden f\u00fcndig. Bevor wir diesen aber n\u00e4her vorstellen, m\u00fcssen wir uns an dieser Stelle noch einmal beim Team von arche noVa bedanken. Denn dort reagierte man zwar mit Bedauern, aber auch mit gro\u00dfem Verst\u00e4ndnis auf die Nachricht, dass wir uns in diesem Jahr gegen ein soziales Projekt ihres Vereins und f\u00fcr eine Unterst\u00fctzung im Ahrtal entschieden hatten. Eine tolle und wirklich ehrenwerte Geste wie wir finden!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>SPENDEN SHUTTLE wird Partner der RED CAP-Spendenaktion 2021<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"400\" height=\"212\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spendenshuttle-logo-foerdahrverein.jpg\" alt=\"\" class=\"wp-image-5201 size-full\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spendenshuttle-logo-foerdahrverein.jpg 400w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spendenshuttle-logo-foerdahrverein-300x159.jpg 300w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spendenshuttle-logo-foerdahrverein-113x60.jpg 113w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spendenshuttle-logo-foerdahrverein-390x208.jpg 390w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Transparenz liegt uns nicht nur in Bezug auf unsere Gew\u00fcrze besonders am Herzen, sondern nat\u00fcrlich auch und gerade wenn es um das soziale Engagement von Hartkorn geht. Deshalb wollen wir dir hier auch noch einmal ganz genau erz\u00e4hlen, wohin wir die <strong>14.500 Euro<\/strong> aus der <strong>RED CAP-Spendenaktion<\/strong> geben und wof\u00fcr sie verwendet werden. <\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Eines war uns nat\u00fcrlich auch in diesem Jahr enorm wichtig: Das Geld sollte genau da ankommen, wo es gebraucht wird. Im Falle der Flutbetroffenen im Ahrtal mussten wir da gar nicht lange \u00fcberlegen und entschieden uns sehr schnell und klar f\u00fcr den neu gegr\u00fcndeten gemeinn\u00fctzigen Verein <strong><a href=\"https:\/\/www.spenden-shuttle.de\/?spenden-shuttle-2\/spende\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-vivid-red-color\">SPENDEN SHUTTLE \u2013 Der F\u00f6rdAHRverein<\/span><\/a><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und jetzt lassen wir die sprichw\u00f6rtliche Katze aber auch endlich aus dem Sack: Die Gelder aus der RED CAP-Aktion kommen dem Projekt <strong>KinderpAHRadies<\/strong> zu Gute.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Kinderaugen sollen leuchten: RED CAP-Spendenaktion unterst\u00fctzt KinderAHRparadies<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gerade das Schicksal von Familien und Kindern, die von der Hochwasserkatastrophe im Ahrtal betroffen sind, geht uns besonders ans Herz. Deshalb freuten wir uns ganz besonders, als <strong>Dirk Gemein, stellvertretender Vorsitzender des SPENDEN SHUTTLE vom Projekt KinderpAHRadies<\/strong> erz\u00e4hlte. <br>\u201eWir bauen einen 800 qm gro\u00dfen Indoorspielplatz mit einem Kinder-Caf\u00e9 f\u00fcr die Kleinen\u201c, erkl\u00e4rte er. Und es gibt noch eine Besonderheit: \u201eF\u00fcr die Flutbetroffenen ist der Eintritt frei\u201c, erz\u00e4hlte uns Dirk. F\u00fcr alle anderen werde der Eintritt auf Spendenbasis erhoben. Ist das nicht toll? Die Er\u00f6ffnung des KinderpAHRadies ist \u00fcbrigens schon f\u00fcr den 01. Februar geplant. Wir sind uns sicher, dass dieses Projekt nicht nur super zu uns von Hartkorn passt, sondern vor allem ein besonders wertvoller Beitrag f\u00fcr die Menschen und Kinder im Ahrtal ist.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021.jpg\" alt=\"Gesch\u00e4ftsf\u00fchrer Dr. Andreas Hartkorn \u00fcbergibt gemeinsam mit seine Frau Simone Hartkorn die Spende an Dirk Gemein vom SPENDEN SHUTTLE \u2013 Der F\u00f6rdAHRverein \" class=\"wp-image-5202\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021.jpg 800w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021-300x200.jpg 300w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021-768x513.jpg 768w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021-90x60.jpg 90w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021-370x247.jpg 370w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/spenden-uebergabe-foerdahrverein-2021-776x517.jpg 776w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:11px\">Spenden\u00fcbergabe des Gesch\u00e4ftsf\u00fchrers Dr. Andreas Hartkorn (links) gemeinsam mit seiner Frau Simone Hartkorn (Mitte) an Dirk Gemein (rechts) den stellvertretenden Vorsitzenden des <em>SPENDEN SHUTTLE \u2013 Der F\u00f6rdAHRverein<\/em> im Dezember 2021<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Du willst noch mehr \u00fcber den Verein und die Arbeit von SPENDEN SHUTTLE \u2013 Der F\u00f6rdAHRverein erfahren? Dann findest du <span class=\"has-inline-color has-vivid-red-color\"><a href=\"https:\/\/www.spenden-shuttle.de\/spendenaktionen\/unsere-spendenprojekte\/\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> <\/span>alle Informationen, die du brauchst.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong><strong>#hartkornhilft: Mit Gummistiefeln und Schippen ins Ahrtal<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na klar, die RED CAP-Spendenaktion ist ein toller und wirklich wichtiger Beitrag f\u00fcr die Hilfe im Ahrtal. Und da m\u00fcssen wir uns nat\u00fcrlich auch bei dir und all unseren Kunden bedanken: <strong>Ohne euch w\u00e4re diese Aktion niemals m\u00f6glich!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber Spenden allein war uns in diesem Fall nicht genug. Immerhin liegt der so schwer getroffene Landkreis Ahrweiler quasi um die Ecke. Da gab es also auch f\u00fcr das Hartkorn Team nur eine L\u00f6sung: selbst mit anpacken! Unter dem #hartkornhilft zogen wir also mit freiwilligen Helfern aus dem Kolleg:innen-Kreis los und schaufelten schubkarrenweise Schlamm aus Schulen, Kinderg\u00e4rten und privaten Wohnungen, Kellern und Garagen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eEs war einfach ein unglaubliches Bild, das sich uns vor Ort bot\u201c, schildert unser Gesch\u00e4ftsf\u00fchrer Andreas Hartkorn seine Eindr\u00fccke. Denn auch er war gleich mit dabei und tatkr\u00e4ftig im Einsatz. \u201eEs tat einfach gut, dass wir zumindest ein kleines bisschen helfen konnten\u201c, lautet sein Fazit. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"746\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkornhilft-collage-hochwasserkatastrophe2021.jpg\" alt=\"Hartkorn Hilft - Aktion im Ahrtal\" class=\"wp-image-5212\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkornhilft-collage-hochwasserkatastrophe2021.jpg 800w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkornhilft-collage-hochwasserkatastrophe2021-300x280.jpg 300w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkornhilft-collage-hochwasserkatastrophe2021-768x716.jpg 768w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2022\/01\/hartkornhilft-collage-hochwasserkatastrophe2021-64x60.jpg 64w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:11px\">Lager- und Verwaltungsmitarbeiter:innen der Firma Hartkorn nutzten ihren Sonderurlaub und packten bei den Betroffenen mit an<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und dieses Gef\u00fchl teilten wohl alle, die mit dabei waren. Mit der RED CAP-Spendenaktion 2021 hallt diese Hilfe nun auch noch einmal nach. Denn auch rund ein halbes Jahr nach der Katastrophe im Ahrtal wird dort noch jede Menge Unterst\u00fctzung auf unterschiedlichste Weise gebraucht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Wann wir in dies n\u00e4chste Runde der RED CAP-Spendenaktion starten, erf\u00e4hrst du nat\u00fcrlich hier oder auf <span class=\"has-inline-color has-vivid-red-color\"><a href=\"https:\/\/www.instagram.com\/hartkorn_gewuerze\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> <\/span>und <span class=\"has-inline-color has-vivid-red-color\">Facebook<\/span>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RED CAP-Spendenaktion unterst\u00fctzt Betroffene der Hochwasserkatastrophe im Ahrtal mit 14.5000 Euro. Das Geld wird an den Spenden Shuttle &#8211; Der F\u00f6rdahrverein gespendet. <\/p>\n","protected":false},"author":6,"featured_media":4798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5,521],"tags":[512,514,158,513],"class_list":["post-5188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten","category-red-cap","tag-hartkornhilft-2","tag-ahrtal","tag-red-cap","tag-spendenshuttle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RED CAP meets SPENDEN SHUTTLE - Hartkorn Gew\u00fcrzm\u00fchle Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RED CAP meets SPENDEN SHUTTLE - Hartkorn Gew\u00fcrzm\u00fchle Blog\" \/>\n<meta property=\"og:description\" content=\"RED CAP-Spendenaktion unterst\u00fctzt Betroffene der Hochwasserkatastrophe im Ahrtal mit 14.5000 Euro. Das Geld wird an den Spenden Shuttle - Der F\u00f6rdahrverein gespendet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/\" \/>\n<meta property=\"og:site_name\" content=\"Hartkorn Gew\u00fcrzm\u00fchle Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/hartkorngewuerze\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-14T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T10:05:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/red-cap-hartkorn-spende-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Svenja Ahlers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Svenja Ahlers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/\"},\"author\":{\"name\":\"Svenja Ahlers\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/person\\\/899979fa3838f209170a42f765ca8ca8\"},\"headline\":\"RED CAP meets SPENDEN SHUTTLE\",\"datePublished\":\"2022-01-14T09:00:00+00:00\",\"dateModified\":\"2023-06-07T10:05:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/\"},\"wordCount\":1099,\"publisher\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/red-cap-hartkorn-spende-7.jpg\",\"keywords\":[\"#hartkornhilft\",\"Ahrtal\",\"Red Cap\",\"Spendenshuttle\"],\"articleSection\":[\"Neuigkeiten\",\"RED CAP\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/\",\"name\":\"RED CAP meets SPENDEN SHUTTLE - Hartkorn Gew\u00fcrzm\u00fchle Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/red-cap-hartkorn-spende-7.jpg\",\"datePublished\":\"2022-01-14T09:00:00+00:00\",\"dateModified\":\"2023-06-07T10:05:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/red-cap-hartkorn-spende-7.jpg\",\"contentUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/red-cap-hartkorn-spende-7.jpg\",\"width\":1300,\"height\":515,\"caption\":\"RED CAP- Spendenaktion f\u00fcr die Betroffenen der Hochwasserkatastrophe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/red-cap-spende-foerdahrverein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RED CAP meets SPENDEN SHUTTLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/\",\"name\":\"Hartkorn Gew\u00fcrze Blog\",\"description\":\"Neuigkeiten, Rezepte, Gew\u00fcrzinformationen\",\"publisher\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#organization\",\"name\":\"Hartkorn Gew\u00fcrze\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_300px.png\",\"contentUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_300px.png\",\"width\":300,\"height\":300,\"caption\":\"Hartkorn Gew\u00fcrze\"},\"image\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/hartkorngewuerze\\\/\",\"https:\\\/\\\/www.instagram.com\\\/hartkorngewuerze\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@hartkorngewuerze\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/person\\\/899979fa3838f209170a42f765ca8ca8\",\"name\":\"Svenja Ahlers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/023c0a3a0628b86fcc99c7aac7e11db53eb588b69a30f424990a1afdd652a72e?s=96&#038;d=mm&#038;r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/023c0a3a0628b86fcc99c7aac7e11db53eb588b69a30f424990a1afdd652a72e?s=96&#038;d=mm&#038;r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/023c0a3a0628b86fcc99c7aac7e11db53eb588b69a30f424990a1afdd652a72e?s=96&#038;d=mm&#038;r=g\",\"caption\":\"Svenja Ahlers\"},\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/author\\\/svenja-sesterhenn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RED CAP meets SPENDEN SHUTTLE - Hartkorn Gew\u00fcrzm\u00fchle Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/","og_locale":"de_DE","og_type":"article","og_title":"RED CAP meets SPENDEN SHUTTLE - Hartkorn Gew\u00fcrzm\u00fchle Blog","og_description":"RED CAP-Spendenaktion unterst\u00fctzt Betroffene der Hochwasserkatastrophe im Ahrtal mit 14.5000 Euro. Das Geld wird an den Spenden Shuttle - Der F\u00f6rdahrverein gespendet.","og_url":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/","og_site_name":"Hartkorn Gew\u00fcrzm\u00fchle Blog","article_publisher":"https:\/\/de-de.facebook.com\/hartkorngewuerze\/","article_published_time":"2022-01-14T09:00:00+00:00","article_modified_time":"2023-06-07T10:05:53+00:00","og_image":[{"width":1300,"height":515,"url":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/red-cap-hartkorn-spende-7.jpg","type":"image\/jpeg"}],"author":"Svenja Ahlers","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Svenja Ahlers","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#article","isPartOf":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/"},"author":{"name":"Svenja Ahlers","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/person\/899979fa3838f209170a42f765ca8ca8"},"headline":"RED CAP meets SPENDEN SHUTTLE","datePublished":"2022-01-14T09:00:00+00:00","dateModified":"2023-06-07T10:05:53+00:00","mainEntityOfPage":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/"},"wordCount":1099,"publisher":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#organization"},"image":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#primaryimage"},"thumbnailUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/red-cap-hartkorn-spende-7.jpg","keywords":["#hartkornhilft","Ahrtal","Red Cap","Spendenshuttle"],"articleSection":["Neuigkeiten","RED CAP"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/","url":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/","name":"RED CAP meets SPENDEN SHUTTLE - Hartkorn Gew\u00fcrzm\u00fchle Blog","isPartOf":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#primaryimage"},"image":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#primaryimage"},"thumbnailUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/red-cap-hartkorn-spende-7.jpg","datePublished":"2022-01-14T09:00:00+00:00","dateModified":"2023-06-07T10:05:53+00:00","breadcrumb":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#primaryimage","url":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/red-cap-hartkorn-spende-7.jpg","contentUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2021\/07\/red-cap-hartkorn-spende-7.jpg","width":1300,"height":515,"caption":"RED CAP- Spendenaktion f\u00fcr die Betroffenen der Hochwasserkatastrophe"},{"@type":"BreadcrumbList","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/red-cap-spende-foerdahrverein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hartkorn-gewuerze.de\/blog\/"},{"@type":"ListItem","position":2,"name":"RED CAP meets SPENDEN SHUTTLE"}]},{"@type":"WebSite","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#website","url":"https:\/\/hartkorn-gewuerze.de\/blog\/","name":"Hartkorn Gew\u00fcrze Blog","description":"Neuigkeiten, Rezepte, Gew\u00fcrzinformationen","publisher":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hartkorn-gewuerze.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#organization","name":"Hartkorn Gew\u00fcrze","url":"https:\/\/hartkorn-gewuerze.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/Logo_300px.png","contentUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/Logo_300px.png","width":300,"height":300,"caption":"Hartkorn Gew\u00fcrze"},"image":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/hartkorngewuerze\/","https:\/\/www.instagram.com\/hartkorngewuerze\/","https:\/\/www.tiktok.com\/@hartkorngewuerze"]},{"@type":"Person","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/person\/899979fa3838f209170a42f765ca8ca8","name":"Svenja Ahlers","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/023c0a3a0628b86fcc99c7aac7e11db53eb588b69a30f424990a1afdd652a72e?s=96&#038;d=mm&#038;r=g","url":"https:\/\/secure.gravatar.com\/avatar\/023c0a3a0628b86fcc99c7aac7e11db53eb588b69a30f424990a1afdd652a72e?s=96&#038;d=mm&#038;r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/023c0a3a0628b86fcc99c7aac7e11db53eb588b69a30f424990a1afdd652a72e?s=96&#038;d=mm&#038;r=g","caption":"Svenja Ahlers"},"url":"https:\/\/hartkorn-gewuerze.de\/blog\/author\/svenja-sesterhenn\/"}]}},"_links":{"self":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts\/5188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/comments?post=5188"}],"version-history":[{"count":27,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts\/5188\/revisions"}],"predecessor-version":[{"id":5239,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts\/5188\/revisions\/5239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/media\/4798"}],"wp:attachment":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/media?parent=5188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/categories?post=5188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/tags?post=5188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}