{"id":199,"date":"2018-06-18T11:23:36","date_gmt":"2018-06-18T09:23:36","guid":{"rendered":"http:\/\/wp.hartkorn-gewuerze.de\/wp2\/?p=199"},"modified":"2022-07-26T13:45:58","modified_gmt":"2022-07-26T11:45:58","slug":"auf-gehts-dahin-wo-der-pfeffer-waechst","status":"publish","type":"post","link":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/","title":{"rendered":"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst!"},"content":{"rendered":"<p>Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Esstisch fehlen. Doch woher stammt er \u00fcberhaupt und wie wird er angebaut? H\u00f6chste Zeit uns das zusammen mit euch einmal n\u00e4her anzuschauen.<\/p>\n<p>Seinen Ursprung hat der Pfeffer in den feuchtwarmen Monsunw\u00e4ldern Asiens. Bereits um 400 v. Chr. wird der Pfeffer in antiken Schriften erw\u00e4hnt und man kann wohl annehmen, dass der Warentransport sowohl mit Schiffen als auch \u00fcber den Landweg von Asien nach Europa erfolgte. Aufgrund seiner langen Haltbarkeit war er n\u00e4mlich das perfekte Fernhandelsgut.<\/p>\n<p>In der damaligen Zeit galt Pfeffer aber noch als besonderer Luxusartikel und wurde zeitweise sogar mit Gold aufgewogen. Erst im Jahre 1498 gelang es dem bekannten Seefahrer Vasco da Gama die erste Ladung Pfeffer von Indien \u00fcber den Seeweg nach Europa zu transportieren. Im Laufe der Jahrhunderte breitete sich der Anbau des kostbaren Guts jedoch zunehmend auf immer mehr Gebiete aus, so dass das verst\u00e4rkte Angebot und die verbesserten Transportm\u00f6glichkeiten schlie\u00dflich daf\u00fcr sorgten, dass der Preis f\u00fcr Pfeffer immer weiter sank und das Gew\u00fcrz somit nicht mehr nur einer exklusiven Schicht vorbehalten war. Das hat sich bis heute nicht ver\u00e4ndert. Die Anbaugebiete liegen dabei mittlerweile haupts\u00e4chlich beiderseits des \u00c4quators, vor allem in Vietnam, Indien, Indonesien und auf Sri Lanka.<\/p>\n<p>Doch wie sieht er eigentlich aus? Der Pfeffer (lat. Piper nigrum) ist eine ausdauernde Kletterpflanze, die eine H\u00f6he von bis zu 10 Metern erreichen kann und zu der Familie der Pfeffergew\u00e4chse geh\u00f6rt. Auf den Plantagen wird er zur Vereinfachung der Kultivierung nur auf einer H\u00f6he von ca. f\u00fcnf Metern gehalten. Der Pfefferstrauch hat 7 bis 15 cm lange ovale Bl\u00e4tter und wei\u00dfe Bl\u00fcten, die in \u00c4hren zusammengefasst sind, \u00e4hnlich wie bei der uns bekannten roten Johannisbeere. Daraus entstehen dann 20 bis 30 erbsengro\u00dfe Beerenfr\u00fcchte die sich im Laufe ihrer Reife von gr\u00fcn zu orangerot verf\u00e4rben.<\/p>\n<p>In der Kultur wird die Pfefferpflanze durch das Setzen einzelner Stecklinge vermehrt, die an B\u00e4umen oder Stangen, wie Hopfen gezogen werden. Ab dem dritten Jahr bringt die Pfefferpflanze Ertrag. Dieser ist nach 7 bis 8 Jahren am gr\u00f6\u00dften und h\u00e4lt bis zum ca. 30. Lebensjahr der Pflanze fast unver\u00e4ndert an. Geerntet werden die Pfefferbeeren dabei zweimal pro Jahr, wobei der Erntezeitpunkt je nach Anbaugebiet unterschiedlich ist.<\/p>\n<p>Der uns bekannte schwarze und wei\u00dfe Pfeffer, sowie der unter Sternek\u00f6chen beliebte gr\u00fcne Pfeffer stammt dabei von ausschlie\u00dflich derselben Pflanze.<\/p>\n<p>Schwarzer Pfeffer wird unreif geerntet. Die zu diesem Zeitpunkt gr\u00fcnen Beeren werden in der Sonne getrocknet bis sie runzlig sind und ihre typische schwarzbraune Farbe erhalten haben. Die getrockneten Pfefferk\u00f6rner haben ein scharfes Aroma, welches sich am besten entfaltet, wenn man die Pfefferk\u00f6rner frisch in der M\u00fchle vermahlt.<\/p>\n<p>Anders als der schwarze Pfeffer wird der wei\u00dfe Pfeffer vollreif (rote Farbe) geerntet und anschlie\u00dfend in S\u00e4cke gef\u00fcllt. Diese S\u00e4cke werden in flie\u00dfendem Wasser eingeweicht. Anschlie\u00dfend wird die weiche Schale mechanisch entfernt und die gesch\u00e4lten Beeren zum Trocknen in die Sonne gelegt bis sie eine gelblich-wei\u00dfe Farbe haben. Der gr\u00fcne Pfeffer wird in unreifem Zustand geerntet und entweder in einer Lake aus Salz oder Essig konserviert, bei hoher Temperatur getrocknet oder sogar gefriergetrocknet.<\/p>\n<p>Egal f\u00fcr welche Variante man sich schlussendlich entscheidet, Pfeffer findet man heutzutage in fast allen K\u00fcchen dieser L\u00e4nder, wo er zum W\u00fcrzen und Verfeinern von Fleischgerichten, Wurstwaren, Fisch, Salaten, So\u00dfen, Suppen, Gem\u00fcse und Marinaden verwendet wird. Kaum ein Gew\u00fcrz ist damit so vielf\u00e4ltig einsetzbar wie Pfeffer! Ein echter Allrounder also, auf den wohl keiner von uns mehr so schnell verzichten m\u00f6chte!<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>Unser Shopping Tipp:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hartkorn-gewuerze.de\/de\/feinkost-pfeffer-gewuerzset.html?utm_source=Blog&amp;utm_medium=Beitrag&amp;utm_campaign=herkunft-pfeffer-tipp-pfeffer-gewuerzset\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/06\/gourmet-glas-pfeffer-1.png\" alt=\"gourmet-glas-pfeffer\" class=\"wp-image-1670\" srcset=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/06\/gourmet-glas-pfeffer-1.png 150w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/06\/gourmet-glas-pfeffer-1-60x60.png 60w, https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/06\/gourmet-glas-pfeffer-1-90x90.png 90w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Esstisch fehlen. Doch woher stammt er \u00fcberhaupt und wie wird er &hellip; <\/p>\n","protected":false},"author":1,"featured_media":232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5],"tags":[176,175],"class_list":["post-199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten","tag-herkunft","tag-pfeffer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst! - Hartkorn Gew\u00fcrzm\u00fchle Blog<\/title>\n<meta name=\"description\" content=\"Woher kommt der Pfeffer und wie wird er angebaut? Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Tisch fehlen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst! - Hartkorn Gew\u00fcrzm\u00fchle Blog\" \/>\n<meta property=\"og:description\" content=\"Woher kommt der Pfeffer und wie wird er angebaut? Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Tisch fehlen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/\" \/>\n<meta property=\"og:site_name\" content=\"Hartkorn Gew\u00fcrzm\u00fchle Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/hartkorngewuerze\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-18T09:23:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T11:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"831\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Svenja Ahlers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Svenja Ahlers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/\"},\"author\":{\"name\":\"Svenja Ahlers\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/person\\\/1ae6439e90966998434e95fecd7528d7\"},\"headline\":\"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst!\",\"datePublished\":\"2018-06-18T09:23:36+00:00\",\"dateModified\":\"2022-07-26T11:45:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/\"},\"wordCount\":630,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg\",\"keywords\":[\"Herkunft\",\"Pfeffer\"],\"articleSection\":[\"Neuigkeiten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/\",\"name\":\"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst! - Hartkorn Gew\u00fcrzm\u00fchle Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg\",\"datePublished\":\"2018-06-18T09:23:36+00:00\",\"dateModified\":\"2022-07-26T11:45:58+00:00\",\"description\":\"Woher kommt der Pfeffer und wie wird er angebaut? Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Tisch fehlen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg\",\"contentUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg\",\"width\":831,\"height\":410,\"caption\":\"hier w\u00e4chst gr\u00fcner Pfeffer f\u00fcr Hartkorn Gew\u00fcrze\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/auf-gehts-dahin-wo-der-pfeffer-waechst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/\",\"name\":\"Hartkorn Gew\u00fcrze Blog\",\"description\":\"Neuigkeiten, Rezepte, Gew\u00fcrzinformationen\",\"publisher\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#organization\",\"name\":\"Hartkorn Gew\u00fcrze\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_300px.png\",\"contentUrl\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_300px.png\",\"width\":300,\"height\":300,\"caption\":\"Hartkorn Gew\u00fcrze\"},\"image\":{\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/hartkorngewuerze\\\/\",\"https:\\\/\\\/www.instagram.com\\\/hartkorngewuerze\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@hartkorngewuerze\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/#\\\/schema\\\/person\\\/1ae6439e90966998434e95fecd7528d7\",\"name\":\"Svenja Ahlers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af58485fc335d40d9e5a639ddb37a1af589a90613c602b64c90b032088c98a6b?s=96&#038;d=mm&#038;r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af58485fc335d40d9e5a639ddb37a1af589a90613c602b64c90b032088c98a6b?s=96&#038;d=mm&#038;r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af58485fc335d40d9e5a639ddb37a1af589a90613c602b64c90b032088c98a6b?s=96&#038;d=mm&#038;r=g\",\"caption\":\"Svenja Ahlers\"},\"url\":\"https:\\\/\\\/hartkorn-gewuerze.de\\\/blog\\\/author\\\/hkwpadmin2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst! - Hartkorn Gew\u00fcrzm\u00fchle Blog","description":"Woher kommt der Pfeffer und wie wird er angebaut? Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Tisch fehlen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/","og_locale":"de_DE","og_type":"article","og_title":"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst! - Hartkorn Gew\u00fcrzm\u00fchle Blog","og_description":"Woher kommt der Pfeffer und wie wird er angebaut? Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Tisch fehlen.","og_url":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/","og_site_name":"Hartkorn Gew\u00fcrzm\u00fchle Blog","article_publisher":"https:\/\/de-de.facebook.com\/hartkorngewuerze\/","article_published_time":"2018-06-18T09:23:36+00:00","article_modified_time":"2022-07-26T11:45:58+00:00","og_image":[{"width":831,"height":410,"url":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg","type":"image\/jpeg"}],"author":"Svenja Ahlers","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Svenja Ahlers","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#article","isPartOf":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/"},"author":{"name":"Svenja Ahlers","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/person\/1ae6439e90966998434e95fecd7528d7"},"headline":"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst!","datePublished":"2018-06-18T09:23:36+00:00","dateModified":"2022-07-26T11:45:58+00:00","mainEntityOfPage":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/"},"wordCount":630,"commentCount":0,"publisher":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#organization"},"image":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#primaryimage"},"thumbnailUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg","keywords":["Herkunft","Pfeffer"],"articleSection":["Neuigkeiten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/","url":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/","name":"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst! - Hartkorn Gew\u00fcrzm\u00fchle Blog","isPartOf":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#primaryimage"},"image":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#primaryimage"},"thumbnailUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg","datePublished":"2018-06-18T09:23:36+00:00","dateModified":"2022-07-26T11:45:58+00:00","description":"Woher kommt der Pfeffer und wie wird er angebaut? Pfeffer ist das beliebteste Gew\u00fcrz auf unserem Planeten und darf neben Salz auf keinem Tisch fehlen.","breadcrumb":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#primaryimage","url":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg","contentUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/auf-geht-s-dahin-wo-der-pfeffer-waechst.jpg","width":831,"height":410,"caption":"hier w\u00e4chst gr\u00fcner Pfeffer f\u00fcr Hartkorn Gew\u00fcrze"},{"@type":"BreadcrumbList","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/auf-gehts-dahin-wo-der-pfeffer-waechst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hartkorn-gewuerze.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Auf geht\u00b4s dahin, wo der Pfeffer w\u00e4chst!"}]},{"@type":"WebSite","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#website","url":"https:\/\/hartkorn-gewuerze.de\/blog\/","name":"Hartkorn Gew\u00fcrze Blog","description":"Neuigkeiten, Rezepte, Gew\u00fcrzinformationen","publisher":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hartkorn-gewuerze.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#organization","name":"Hartkorn Gew\u00fcrze","url":"https:\/\/hartkorn-gewuerze.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/Logo_300px.png","contentUrl":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-content\/uploads\/2020\/04\/Logo_300px.png","width":300,"height":300,"caption":"Hartkorn Gew\u00fcrze"},"image":{"@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/hartkorngewuerze\/","https:\/\/www.instagram.com\/hartkorngewuerze\/","https:\/\/www.tiktok.com\/@hartkorngewuerze"]},{"@type":"Person","@id":"https:\/\/hartkorn-gewuerze.de\/blog\/#\/schema\/person\/1ae6439e90966998434e95fecd7528d7","name":"Svenja Ahlers","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/af58485fc335d40d9e5a639ddb37a1af589a90613c602b64c90b032088c98a6b?s=96&#038;d=mm&#038;r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af58485fc335d40d9e5a639ddb37a1af589a90613c602b64c90b032088c98a6b?s=96&#038;d=mm&#038;r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af58485fc335d40d9e5a639ddb37a1af589a90613c602b64c90b032088c98a6b?s=96&#038;d=mm&#038;r=g","caption":"Svenja Ahlers"},"url":"https:\/\/hartkorn-gewuerze.de\/blog\/author\/hkwpadmin2\/"}]}},"_links":{"self":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts\/199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/comments?post=199"}],"version-history":[{"count":7,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts\/199\/revisions"}],"predecessor-version":[{"id":6398,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/posts\/199\/revisions\/6398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/media\/232"}],"wp:attachment":[{"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/media?parent=199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/categories?post=199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hartkorn-gewuerze.de\/blog\/wp-json\/wp\/v2\/tags?post=199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}